{"id":2518,"date":"2021-10-29T10:00:31","date_gmt":"2021-10-29T08:00:31","guid":{"rendered":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/"},"modified":"2024-03-02T15:22:14","modified_gmt":"2024-03-02T14:22:14","slug":"les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985","status":"publish","type":"post","link":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/","title":{"rendered":"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985"},"content":{"rendered":"<p>Extrait conference colonel  Allemand sur les services allemands pendant la 1ere guerre mondiales . Selons un bilan quantitatif, durant les trois premi\u00e8res ann\u00e9es de la  guerre, 1785 personnes furent arr\u00eat\u00e9es en Allemagne pour port ill\u00e9gal  \u2018uniforme (la plupart travaillant pour la France.)- 384 faux officiers furent identifi\u00e9s derri\u00e8re les lignes. 500 personnes furent  pass\u00e9es par les armes, dont la moiti\u00e9 \u00e9tait au service de notre pays. En 1918, 33 condamnations furent prononc\u00e9es pour sabotages, dont 32 organis\u00e9s par la France.<\/p>\n<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-bottom-right\"><a href=\"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2518?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" data-src=\"https:\/\/aassdn.org\/amicale\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;\" \/><\/a><a href=\"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2518?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Extrait conference colonel Allemand sur les services allemands pendant la 1ere guerre mondiales . Selons un bilan quantitatif, durant les trois premi\u00e8res ann\u00e9es de la guerre, 1785 personnes furent arr\u00eat\u00e9es en Allemagne pour port ill\u00e9gal \u2018uniforme (la plupart travaillant pour la France.)- 384 faux officiers furent identifi\u00e9s derri\u00e8re les lignes. 500 personnes furent pass\u00e9es par [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[114,79,99],"tags":[293,360,465,490,346,736,309,725,667,720],"class_list":["post-2518","post","type-post","status-publish","format-standard","hentry","category-europe-de-louest","category-extraits-de-bulletin","category-services-allemands","tag-allemagne","tag-allemands","tag-colonisation","tag-conference","tag-guerre","tag-officier","tag-sabotage","tag-sabotages","tag-services","tag-services-allemands"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985 | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985 | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\" \/>\n<meta property=\"og:description\" content=\"Extrait conference colonel Allemand sur les services allemands pendant la 1ere guerre mondiales . Selons un bilan quantitatif, durant les trois premi\u00e8res ann\u00e9es de la guerre, 1785 personnes furent arr\u00eat\u00e9es en Allemagne pour port ill\u00e9gal \u2018uniforme (la plupart travaillant pour la France.)- 384 faux officiers furent identifi\u00e9s derri\u00e8re les lignes. 500 personnes furent pass\u00e9es par [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/\" \/>\n<meta property=\"og:site_name\" content=\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-29T08:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-02T14:22:14+00:00\" \/>\n<meta name=\"author\" content=\"AASSDN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AASSDN\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\\\/\"},\"author\":{\"name\":\"AASSDN\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/person\\\/73800712a272e6d58a10a86ea9e59671\"},\"headline\":\"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985\",\"datePublished\":\"2021-10-29T08:00:31+00:00\",\"dateModified\":\"2024-03-02T14:22:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\\\/\"},\"wordCount\":96,\"publisher\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#organization\"},\"keywords\":[\"Allemagne\",\"Allemands\",\"Colonisation\",\"conf\u00e9rence\",\"guerre\",\"Officier\",\"sabotage\",\"sabotages\",\"Services\",\"services allemands\"],\"articleSection\":[\"Europe de l'Ouest\",\"Extraits de bulletin\",\"Services allemands\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\\\/\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\\\/\",\"name\":\"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985 | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#website\"},\"datePublished\":\"2021-10-29T08:00:31+00:00\",\"dateModified\":\"2024-03-02T14:22:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aassdn.org\\\/amicale\\\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#website\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/\",\"name\":\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\",\"description\":\"Services sp\u00e9ciaux : Des h\u00e9ros anonymes au service exclusif de la France\",\"publisher\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#organization\",\"name\":\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/wp-content\\\/uploads\\\/Logo_AASSDN_transparent2.png\",\"contentUrl\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/wp-content\\\/uploads\\\/Logo_AASSDN_transparent2.png\",\"width\":1832,\"height\":1609,\"caption\":\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\"},\"image\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/person\\\/73800712a272e6d58a10a86ea9e59671\",\"name\":\"AASSDN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g\",\"caption\":\"AASSDN\"},\"sameAs\":[\"https:\\\/\\\/aassdn.org\\\/amicale\"],\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/author\\\/wordpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985 | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985 | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","og_description":"Extrait conference colonel Allemand sur les services allemands pendant la 1ere guerre mondiales . Selons un bilan quantitatif, durant les trois premi\u00e8res ann\u00e9es de la guerre, 1785 personnes furent arr\u00eat\u00e9es en Allemagne pour port ill\u00e9gal \u2018uniforme (la plupart travaillant pour la France.)- 384 faux officiers furent identifi\u00e9s derri\u00e8re les lignes. 500 personnes furent pass\u00e9es par [&hellip;]","og_url":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/","og_site_name":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","article_published_time":"2021-10-29T08:00:31+00:00","article_modified_time":"2024-03-02T14:22:14+00:00","author":"AASSDN","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"AASSDN"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/#article","isPartOf":{"@id":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/"},"author":{"name":"AASSDN","@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/person\/73800712a272e6d58a10a86ea9e59671"},"headline":"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985","datePublished":"2021-10-29T08:00:31+00:00","dateModified":"2024-03-02T14:22:14+00:00","mainEntityOfPage":{"@id":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/"},"wordCount":96,"publisher":{"@id":"https:\/\/aassdn.org\/amicale\/#organization"},"keywords":["Allemagne","Allemands","Colonisation","conf\u00e9rence","guerre","Officier","sabotage","sabotages","Services","services allemands"],"articleSection":["Europe de l'Ouest","Extraits de bulletin","Services allemands"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/","url":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/","name":"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985 | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","isPartOf":{"@id":"https:\/\/aassdn.org\/amicale\/#website"},"datePublished":"2021-10-29T08:00:31+00:00","dateModified":"2024-03-02T14:22:14+00:00","breadcrumb":{"@id":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aassdn.org\/amicale\/les-services-speciaux-francais-pendant-la-premiere-guerre-mondiale-2-n-128-1985\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aassdn.org\/amicale\/"},{"@type":"ListItem","position":2,"name":"Les Services speciaux francais pendant la premiere guerre mondiale (2)- n 128- 1985"}]},{"@type":"WebSite","@id":"https:\/\/aassdn.org\/amicale\/#website","url":"https:\/\/aassdn.org\/amicale\/","name":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","description":"Services sp\u00e9ciaux : Des h\u00e9ros anonymes au service exclusif de la France","publisher":{"@id":"https:\/\/aassdn.org\/amicale\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aassdn.org\/amicale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aassdn.org\/amicale\/#organization","name":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","url":"https:\/\/aassdn.org\/amicale\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/logo\/image\/","url":"https:\/\/aassdn.org\/amicale\/wp-content\/uploads\/Logo_AASSDN_transparent2.png","contentUrl":"https:\/\/aassdn.org\/amicale\/wp-content\/uploads\/Logo_AASSDN_transparent2.png","width":1832,"height":1609,"caption":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux"},"image":{"@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/person\/73800712a272e6d58a10a86ea9e59671","name":"AASSDN","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g","caption":"AASSDN"},"sameAs":["https:\/\/aassdn.org\/amicale"],"url":"https:\/\/aassdn.org\/amicale\/author\/wordpress\/"}]}},"_links":{"self":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/comments?post=2518"}],"version-history":[{"count":0,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2518\/revisions"}],"wp:attachment":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/media?parent=2518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/categories?post=2518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/tags?post=2518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}