{"id":2403,"date":"2021-10-29T10:00:21","date_gmt":"2021-10-29T08:00:21","guid":{"rendered":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/"},"modified":"2024-03-15T14:07:03","modified_gmt":"2024-03-15T13:07:03","slug":"souvenirs-de-deportation-2","status":"publish","type":"post","link":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/","title":{"rendered":"Souvenirs de deportation (2)"},"content":{"rendered":"<p>Le Kommando venu de NEUENGAMME est employ\u00e9 au \u201d d\u00e9gagement \u201d des bombes non       \u00e9clat\u00e9es et les matin\u00e9es de ce dangereux travail se passent \u00e0 approcher au       plus pr\u00e8s et surtout au plus profond possible de l\u2019engin rep\u00e9r\u00e9 ce qui       pla\u00e7ait alors les d\u00e9port\u00e9s \u00e0 l\u2019abri \u2026 des vues du personnel d\u2019escorte,       celui-ci se tenant, bien entendu, prudemment \u00e0 distance)<br \/>            Lorsque par la gr\u00e2ce de Dieu, la bombe r\u00e9pondait \u00e0 l\u2019appel de la sonde, la       joie r\u00e9gnait parmi les terrassiers; d\u00e8s cet instant, en effet, le travail       pouvait se poursuivre \u00e0 l\u2019extr\u00eame ralenti; il n\u2019y avait plus de myst\u00e8re       vis-\u00e0-vis des \u201cschupos \u201d qui demeuraient toujours invisibles, le travail       continuait, mat\u00e9rialis\u00e9 par des bruits divers de pelles et de pioches, au       rythme rapide de la matin\u00e9e.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Que de quarts d\u2019heure (et d\u2019heures !) avons-nous ainsi vol\u00e9 au service de       d\u00e9minage de la Wehrmacht ?             A force de se relayer, \u00e0 force de creuser (ce fut quelquefois sans espoir \ud83d\ude42       une des deux sous-\u00e9quipes se trouvait soudain en pr\u00e9sence de la bombe : elle       \u00e9tait l\u00e0, verticale ou inclin\u00e9e, parfois horizontale, cachant sa charge de       poudre et montrant son dangereux dispositif d\u2019explosion. Un soupir sortait       de nos poitrines car nous savions bien qu\u2019un tr\u00e8s l\u00e9ger coup de pioche e\u00fbt       quelquefois suffi \u00e0 nous faire passer, en une fraction de seconde, de vie \u00e0       tr\u00e9pas.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Vers 18 heures, un tr\u00e8s dynamique artificier de la Wehrmacht se rendait       aupr\u00e8s de chaque \u00e9quipe pour contr\u00f4ler le travail; il d\u00e9samor\u00e7ait lui-m\u00eame       les bombes qui se trouvaient d\u00e9gag\u00e9es.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Dans une atmosph\u00e8re d\u2019absolue s\u00e9curit\u00e9, on fumait alors une cigarette,       offerte par lui, en attendant le camion qui devait nous reconduire dans       notre baraque.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Durant la p\u00e9riode du 26 Juillet au 31 Ao\u00fbt, date \u00e0 laquelle je quittai KIEL       avec quelques camarades, chaque \u00e9quipe avait en moyenne d\u00e9gag\u00e9 une bombe par       jour; le chiffre total s\u2019\u00e9levait donc, pour l\u2019ensemble du kommando, \u00e0       environ 450.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">\u201d Les Anglais fabriquent de mauvaises bombes, une sur quinze n\u2019\u00e9clate pas \u201d       m\u2019avait confi\u00e9 un jour l\u2019artificier. C\u2019\u00e9tait me d\u00e9voiler que 6.300 bombes       \u00e9taient tomb\u00e9es sur KIEL et avaient effectivement \u00e9clat\u00e9 :             Beau travail !<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Cependant il n\u2019y avait pour nous ni dimanches ni jours f\u00e9ri\u00e9s, nous       travaillions comme en semaine, de 7 heures du matin \u00e0 8 heures du soir. J\u2019ai       pr\u00e9sent \u00e0 la m\u00e9moire le jour du 15 Ao\u00fbt au cours duquel nous n\u2019avons cess\u00e9       de creuser sous une chaleur accablante. Le d\u00e9couragement et le d\u00e9sespoir       s\u2019emparaient de nous; nous \u00e9tions obs\u00e9d\u00e9s par l\u2019id\u00e9e que PARIS allait \u00eatre       ou \u00e9tait d\u00e9j\u00e0 \u00e9vacu\u00e9 par l\u2019arm\u00e9e allemande, et nous voyions de notre       lointaine terre d\u2019exil, Parisiens et Parisiennes f\u00eater joyeusement la       Lib\u00e9ration.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Combien de fois ai-je ce jour l\u00e0, pens\u00e9 \u00e0 tous les miens, \u00e0 mon       patron de la R\u00e9sistance, \u00e0 mes amis et \u00e0 mes camarades : je n\u2019\u00e9tais pas seul       \u00e0 m\u2019\u00e9vader dans ces r\u00eaves, car le silence entre nous \u00e9tait complet. Nous       n\u2019entendions que le cliquetis monotone des outils, et parfois, quelque       d\u00e9licieux chant d\u2019oiseaux.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Le lendemain, l\u2019\u00e9quipe \u00e0 laquelle j\u2019appartenais fut d\u00e9sign\u00e9e pour accomplir       une mission particuli\u00e8re. On nous conduisit au canal de KIEL pour retirer un       cadavre qui flottait \u00e0 quelques m\u00e8tres de la berge. C\u2019\u00e9tait le corps d\u2019un       malheureux aviateur anglais que la mer avait pouss\u00e9 jusque l\u00e0. Il \u00e9tait       affreusement gonfl\u00e9; par endroits, des lambeaux de chair pendaient; sa face       \u00e9tait rong\u00e9e.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Pauvre ami anglais, tu \u00e9tais lourd sur nos \u00e9paules et souvent, tu voulais       t\u2019\u00e9chapper. Ce sont quatre Fran\u00e7ais qui t\u2019ont pos\u00e9 sur une civi\u00e8re et qui se       sont, un instant, recueillis devant toi.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Le bruit avait couru au moment de notre arriv\u00e9e \u00e0 KIEL, que nous \u00e9tions des       condamn\u00e9s de droit commun, des bandits, des assassins et des \u2026 \u201d terroristes       \u201c. Le terme de terroriste se devinait sur toutes les bouches lorsque nous       traversions la ville pour nous rendre au travail, et semait un certain       d\u00e9sordre dans les rues ou sur les places publiques. Le fait suivant       illustrera la peur qu\u2019\u00e9prouvait devant nos uniformes de bagnards la       population de la ville.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Au d\u00e9but du mois d\u2019Ao\u00fbt, deux \u00e9quipes avaient \u00e9t\u00e9 d\u00e9sign\u00e9es pour aller       d\u00e9gager deux bombes non \u00e9clat\u00e9es qui venaient de traverser un immeuble de 6       \u00e9tages. Une foule compacte se serrait autour du cordon interdisant l\u2019acc\u00e8s       du terrain dangereux. Soudain, cette foule disparut comme une vol\u00e9e de       moineaux ; les \u201d terroristes \u201d arrivaient .<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Nous e\u00fbmes l\u2019occasion, par la suite, de constater un revirement dans       l\u2019attitude de la population. Lorsqu\u2019en fin de journ\u00e9e, par exemple, les       camions nous reconduisaient vers notre baraque, plus d\u2019une main anonyme nous       jeta en cachette quelque friandise ou quelques cigarettes.<br \/>            * *<br \/>            Nous sommes le 25 Ao\u00fbt 1944; mes trois camarades et moi travaillons d\u00e9j\u00e0       depuis de longues heures sous une chaleur tropicale. Nous ne sommes pas       encore pr\u00eats de trouver la bombe qui est venue s\u2019enfoncer dans un terrain       sablonneux qui s\u2019\u00e9boule sans cesse. Nous avons soif, terriblement soif.       Friedrich et Walter, nos deux gardiens, nous font cesser le travail et       Friedrich me demande de l\u2019accompagner au village le plus proche pour aller       chercher quelques litres d\u2019eau. Nous marchons longtemps sous la grande       chaleur avant d\u2019atteindre la premi\u00e8re maison dans laquelle nous p\u00e9n\u00e9trons.       Dans le couloir je tombe \u00e0 terre, ext\u00e9nu\u00e9. Friedrich sonne \u00e0 la porte et       r\u00e9clame un seau d\u2019eau \u00e0 la ma\u00eetresse de maison; aupr\u00e8s d\u2019elle se tient son       fils \u00e2g\u00e9 de 12 ans environ.<br \/>            Un dialogue significatif :             Pendant l\u2019absence de sa m\u00e8re, le jeune gar\u00e7on entame une conversation avec       Friedrich et j\u2019entends, dans mon \u00e9puisement, le bref dialogue suivant qui       m\u00e9rite d\u2019\u00eatre rapport\u00e9 :             Le jeune gar\u00e7on me montrant du doigt : \u2013 Qu\u2019est-ce que c\u2019est que celui-l\u00e0 ? \u2013 Friedrich : C\u2019est un prisonnier fran\u00e7ais. \u2013 Le gosse : o\u00f9 travaille-t-il ?             \u2013 Friedrich : A la campagne, aux bombes             \u2013 Le gosse : Ah, tant mieux :             \u2013 Friedrich ; Pourquoi ? \u2013 Le gosse : Parce que les Fran\u00e7ais sont nos ennemis h\u00e9r\u00e9ditaires. Pourquoi       n\u2019abats-tu pas celui-l\u00e0 tout de suite avec ton fusil ? \u2013 Friedrich : Tu es trop petit pour comprendre. Sache seulement que c\u2019est un       homme comme moi et d\u2019autres Allemands \u2026. <br \/>Dans les derniers jours du mois d\u2019Ao\u00fbt, le travail tirait \u00e0 sa fin; le S.S.       re\u00e7ut l\u2019ordre de r\u00e9duire l\u2019effectif du kommando et de renvoyer 20 hommes au       camp de NEUENGAMME.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Un sentiment me dicta d\u2019\u00eatre volontaire pour partir; je       ne fus d\u2019ailleurs pas le seul \u00e0 vouloir changer d\u2019air, car le travail \u00e9tait       trop dangereux. Si jusque-l\u00e0 il n\u2019y avait eu aucun accident c\u2019\u00e9tait, nous le       savions, l\u2019effet du hasard.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Le S.S. n\u2019avait d\u2019ailleurs jamais manqu\u00e9 de       semer l\u2019angoisse parmi nous en nous annon\u00e7ant notamment que plusieurs       \u00e9quipes du kommando de HAMBOURG avaient disparu dans les airs en moins d\u2019une       semaine.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Le 30 Ao\u00fbt, les 20 hommes d\u00e9sign\u00e9s pour partir prirent cong\u00e9 des       autres plus ou moins volontaires pour demeurer \u00e0 KIEL. Nos adieux, empreints       d\u2019une grande cordialit\u00e9 (on chanta et on s\u2019embrassa), ne plurent gu\u00e8re au       S.S. qui nous s\u00e9para assez brutalement et nous interdit de parler et de       bouger.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Le camion des 20 partants arriva pr\u00e8s de la baraque et lorsque, peu apr\u00e8s il       d\u00e9marra, tous les bras s\u2019agit\u00e8rent en signe d\u2019adieu et tout le monde cria \u201d       \u00e0 bient\u00f4t \u201c.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            L\u2019allure du camion est rapide, on dirait que le chauffeur est, press\u00e9 de       nous faire conna\u00eetre le sort qui nous attend.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Nous parlons beaucoup des camarades rest\u00e9s \u00e0 KIEL et, en particulier de       l\u2019\u00e9quipe de la cantine de l\u2019arsenal qui, avant notre d\u00e9part, a donn\u00e9 \u00e0       chacun de nous quelques pinc\u00e9es de tabac. (Elle en avait un petit stock dans       un endroit secret ).<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Le paysage \u00e0 travers le Schleswig-Holstein est joli.       Nous traversons NEUMUNSTER, petite ville tr\u00e8s riante, o\u00f9 les m\u00e9nag\u00e8res       venant du march\u00e9 rentrent chez elles avec des paniers pleins.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Les schupos qui nous accompagnent manifestent une humeur excellente; ils       commentent \u2013 chose incroyable \u2013 les nouvelles de la radio anglaise, et       j\u2019apprends que BRUXELLES a \u00e9t\u00e9 abandonn\u00e9e par les Allemands. De joie, je       roule une cigarette.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Nous apercevons au loin une immense \u00e9tendue gris\u00e2tre. C\u2019est HAMBOURG. Nous       traversons la ville et sur plusieurs kilom\u00e8tres, nous voyons des maisons       effondr\u00e9es et des installations industrielles r\u00e9duites \u00e0 des tas de       ferraille. C\u00e0 et l\u00e0 des troupes de gens attendent devant des fruitiers ou       des boulangers.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Un sentiment de satisfaction nous envahit. \u201d La guerre ne peut plus durer       107 ans \u201d lance un camarade auquel un Schupo (qui a compris) r\u00e9plique avec       persuasion : \u201d Non, dans trois mois, tout sera fini \u201c.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Une partie de la longue route qui relie HAMBOURG \u00e0 NEUENGAMME est bord\u00e9e       tous les 20 ou 30 m\u00e8tres d\u2019amas de pierres ou de briques, vestiges de villas       qui avaient d\u00fb ressembler \u00e0 celles de St-Cloud ou de St-Germain, et dont       quelques directeurs d\u2019usines ou membres influents du parti \u00e9taient       vraisemblablement propri\u00e9taires. Aucune de ces maisons n\u2019a \u00e9t\u00e9 \u00e9pargn\u00e9e;       nous avons compt\u00e9 des centaines de d\u00e9combres.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Le camp de NEUENGAMME est maintenant en vue. Plus nous approchons, plus nous       devenons silencieux. Nous regrettons d\u2019avoir quitt\u00e9 le groupe sympathique de       KIEL et ignorons ce que nous allons devenir.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\"><strong>Retour \u00e0 NEUENGAM<\/strong><\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            D\u00e8s l\u2019entr\u00e9e dans le camp, nous assistons, mes camarades et moi, \u00e0 un       spectacle qui en dit long sur l\u2019\u00e9tat d\u2019esprit r\u00e9gnant alors entre la       Wehrmacht et les S.S. : paraissant inquiets et fatigu\u00e9s, 19 Sous-officiers de       la Wehrmacht sont align\u00e9s sur la grande place d\u2019appel; soudain arrivent deux       S.S, qui les d\u00e9s\u00e9quipent, se font remettre leurs objets personnels et       proc\u00e8dent ensuite, selon les r\u00e8gles de \u201d l\u2019art \u201c, \u00e0 un s\u00e9rieux \u201d passage \u00e0       tabac \u201d de leurs victimes.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">L\u2019un des deux leur cingle le visage avec un       ceinturon tandis que l\u2019autre leur distribue sans compter de magistraux coups       de bottes au derri\u00e8re. Les Sous-officiers de la Wehrmacht qui ont \u201d encaiss\u00e9       \u201d les coups sans broncher, sont pourchass\u00e9s comme des chiens jusqu\u2019\u00e0 la       porte de la prison du camp. Le bruit courut le m\u00eame jour qu\u2019ils devaient       \u00eatre pendus le lendemain; sans doute avaient-ils \u00e9t\u00e9 m\u00eal\u00e9s \u00e0 la conspiration       du 20 Juillet.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Cet incident grave renfor\u00e7a l\u2019espoir que nous avions d\u00e9j\u00e0 de rentrer bient\u00f4t       en France; pour nous, une chose pareille signifiait une r\u00e9volution au sein       de l\u2019arm\u00e9e allemande et, partant, une fin rapide de la guerre.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Tous nos anciens camarades de COMPIEGNE en rentrant du travail ce soir-l\u00e0 se       r\u00e9jouirent de cet \u00e9v\u00e8nement. Harass\u00e9s par leur dure besogne (lls       d\u00e9chargeaient des p\u00e9niches \u00e0 longueur de journ\u00e9e), cette nouvelle leur       apporta un v\u00e9ritable r\u00e9confort. Jamais depuis notre d\u00e9part de France, notre       moral n\u2019avait \u00e9t\u00e9 meilleur.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Notre s\u00e9jour \u00e0 NEUENGAMME ne devait pas \u00eatre de longue dur\u00e9e, d\u00e8s notre       arriv\u00e9e au camp on parlait d\u00e9j\u00e0 de l\u2019envoi d\u2019un kommando de 60 hommes pour       les environs de HANNOVER. Ferions-nous partie de ce convoi ou \u2026 d\u2019un autre       qui serait form\u00e9 plus tard ? Nous ne le savions pas. En tous cas,       l\u2019administration du camp prit soin de nous ; les 20 \u00ab Ki\u00e9lois \u00bb pass\u00e8rent       aux douches, au \u201d coiffeur \u201c, et re\u00e7urent en \u00e9change de leurs loques       crasseuses, un uniforme propre et \u2026 bien repass\u00e9.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Le lendemain s\u2019\u00e9coula assez calmement; personne d\u2019entre nous ne partit       travailler. C\u2019\u00e9tait l\u2019indice certain d\u2019un tr\u00e8s proche d\u00e9part. Le jour       suivant, on nous rassembla sur la grande place du camp o\u00f9 40 russes et       polonais se trouvaient d\u00e9j\u00e0.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Le sort en \u00e9tait jet\u00e9 : nous partions avec eux dans les environs de HANNOVER.             Notre embarquement se fit en gare de NEUENGAMME, en fin de matin\u00e9e. Le       kommando avait \u00e9t\u00e9 divis\u00e9 en deux groupes de 30 hommes,occupant chacun un       wagon-\u00e0-bestiaux.<br \/>            Malgr\u00e9 ce confort relatif, le souvenir de l\u2019embarquement du 15 Juillet       (Compi\u00e8gne) me revint \u00e0 l\u2019esprit avec intensit\u00e9; je mesurai le chemin que       j\u2019avais parcouru.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Qu\u2019allions-nous maintenant devenir ? Quand nous dirigerions-nous enfin vers       le Rhin et vers Paris ? Pour 1\u2019instant, nous traversions une grande for\u00eat       recouverte de bruy\u00e8res qui scintillaient au soleil. C\u2019\u00e9tait la \u201d L\u00fcneburger       Heide\u201d, paysage magnifique, respirant la paix et qui \u00e9veilla en nous       certaine tentation.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Il ne fallait cependant pas y songer; nos nombreux       gardiens, r\u00e9partis dans deux wagons-voyageurs qui encadraient les n\u00f4tres,       veillaient sur nous. C\u2019eut \u00e9t\u00e9 d\u2019essayer de mettre nos r\u00eaves \u00e0 ex\u00e9cution.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\"><strong>\u2013 V \u2013 Au CAMP de HANNOVER-MISBURG<\/strong>             (2 Septembre \u2013 2 Novembre 1944)<br \/>            Le train stoppa vers 8 heures du soir en gare de MISBURG : on forma les       rangs rapidement et la colonne se mit aussit\u00f4t en route vers le camp. Le       Sous-officier S.S. qui commandait le d\u00e9tachement ne voulut pas manquer de se       signaler \u00e0 cette occasion en bottant s\u00e9rieusement le derri\u00e8re de quelques       malheureux tra\u00eenards ou de quelques autres qui n\u2019avaient pas, \u00e0 son gr\u00e9, une       allure suffisamment martiale.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">A notre gauche s\u2019\u00e9tendait sur plusieurs kilom\u00e8tres. la raffinerie de p\u00e9trole       dont nous avait parl\u00e9 un gardien au moment de notre arriv\u00e9e en gare.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Ses nombreuses chemin\u00e9es l\u00e9zard\u00e9es ou renvers\u00e9es, ses grands r\u00e9servoirs       inclin\u00e9s ou compl\u00e8tement aplatis t\u00e9moignaient \u2013 \u00e0 notre vive satisfaction \u2013       de nombreux passages efficaces de bombardiers lourds.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Bient\u00f4t nous v\u00eemes au loin, au milieu d\u2019un pr\u00e9, quatre tentes immenses       autour desquelles circulaient en nombre consid\u00e9rable des \u201cbagnards\u201d qui       portaient l\u2019uniforme bleu et blanc. Sans aucun doute, c\u2019\u00e9tait l\u00e0 que nous       nous rendions.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Notre arriv\u00e9e ne passa pas inaper\u00e7ue, car nous f\u00fbmes aussit\u00f4t       entour\u00e9s par les d\u00e9tenus du camp qui, sauf quelques Fran\u00e7ais et quelques       Belges, nous r\u00e9serv\u00e8rent un accueil assez froid et m\u00eame hostile; une grande       partie d\u2019entre eux nous fit comprendre par toutes sortes de gestes, que nous       pouvions nous pr\u00e9parer \u00e0 \u00eatre maltrait\u00e9s.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Le \u201cdoyen\u201d du camp, un Allemand,       condamn\u00e9 de droit commun, se trouva quelque peu embarrass\u00e9 pour nous loger.       Apr\u00e8s s\u2019\u00eatre enquis aupr\u00e8s de ses 4 sous-ordres, chefs de \u201d block \u201d , des       possibilit\u00e9s de couchage, il appela le \u201d docteur \u201d du camp (un \u00e9tudiant en       m\u00e9decine, fran\u00e7ais)<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">et nous entend\u00eemes avec stup\u00e9faction le dialogue suivant       :   \u2013 Le \u201cdoyen\u201d :\u201d J\u2019ai encore besoin de 8 ch\u00e2lits pour coucher les derniers;       combien y a-t-il de morts aujourd\u2019hui ? \u201d   Le \u201cdocteur\u201d : \u201d trois \u201d   Le \u201cdoyen\u201d : \u201d trois seulement ? \u201d   Le \u201cdocteur\u201d (\u00e0 part et tout bas) : \u201d c\u2019est bien suffisant \u201c.   Le \u201cdoyen\u201d (s\u2019adressant alors aux chefs de block) :  \u201d J\u2019esp\u00e8re qu\u2019il y aura       d\u2019autres morts cette nuit; demain nous pourrons loger les derniers; pour       l\u2019instant, qu\u2019ils s\u2019arrangent \u201c\u2026<br \/>            Telle fut notre premi\u00e8re prise de contact avec le camp de MISBURG.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            L\u2019effectif du camp \u00e9tait de 1.600 hommes environ. Chaque tente en abritait       400. Grosso modo, on comptait 50 % de Russes, 40 % de Polonais et 10 % de       Fran\u00e7ais et Belges.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">L\u2019unique ameublement de la tente comprenait 130 ch\u00e2lits       \u00e0 3 \u00e9tages pos\u00e9s \u00e0 m\u00eame le sol et s\u00e9par\u00e9s entre eux par de tr\u00e8s \u00e9troits       passages; il y avait aussi \u2013 \u00e0 tout seigneur tout honneur \u2013 le ch\u00e2lit, la       table et le tabouret personnel du \u201d Kapo \u201d (ainsi s\u2019appelait le chef de       block); ils \u00e9taient plac\u00e9s \u00e0 l\u2019extr\u00e9mit\u00e9 de la porte d\u2019entr\u00e9e, seul endroit       o\u00f9 il y avail un peu d\u2019air et de lumi\u00e8re.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Faute de place, les d\u00e9tenus n\u2019avaient pas de r\u00e9fectoire; pour manger, ils       s\u2019installaient dans la cour du camp. Par mauvais temps, le \u201d Kapo \u201d       distribuait la soupe \u00e0 l\u2019int\u00e9rieur de la tente mais la cohue \u00e9tait telle,       pendant et apr\u00e8s la distribution, que beaucoup de d\u00e9tenus pr\u00e9f\u00e9raient aller       manger sous la pluie ou .. dans les cabinets.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Le \u201cKapo\u201d \u00e9tait responsable devant le \u201cdoyen\u201d de l\u2019ordre et de la discipline       \u00e0 l\u2019int\u00e9rieur de son \u201cblock\u201d. Il \u00e9tait second\u00e9 par quelques Allemands, comme       lui condamn\u00e9s de droit commun, qui briguaient d\u2019ailleurs sa place. Il       voulait constamment \u00eatre tenu au courant des faits et gestes de ses for\u00e7ats;       il \u00e9tait \u00e0 cet effet entour\u00e9 d\u2019une trentaine d\u2019informateurs ou conseillers       qu\u2019il choisissait parmi les plus jeunes d\u00e9tenus et qu\u2019il r\u00e9partissait \u00e0       l\u2019int\u00e9rieur du \u201d block \u201c.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Cet Etat-Major auquel venait encore s\u2019ajouter le coiffeur, le portier et le       balayeur, menait une vie joyeuse : plusieurs fois par semaine, les \u00e9lus se       r\u00e9unissaient la nuit autour de la table du Kapo pour festoyer. Que de       rations appartenant \u00e0 la collectivit\u00e9 ont ainsi \u00e9t\u00e9 englouties. Que de coups       de matraque ont \u00e9t\u00e9 donn\u00e9s \u00e0 ceux qui, par malheur, avaient eu l\u2019audace de       s\u2019insurger contre de pareils proc\u00e9d\u00e9s.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            A 5 heures, quelques brefs coups de sifflet annon\u00e7aient l\u2019heure du r\u00e9veil;       il fallait faire vite pour se lever car les fid\u00e8les adjoints du \u201d Kapo \u201d       maniaient la matraque avec facilit\u00e9.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            H\u00e2t\u00e9s de retourner sa paillasse et de ramasser les nombreux petits brins de       paille qui se trouvaient sur le sol plein de crachats.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Les 1.600 d\u00e9tenus du camp ne disposaient que de 30 robinets pour faire leur       toilette; il est vrai que beaucoup d\u2019entre eux ne se lavaient que tous les       deux ou trois jours ou m\u00eame pas du tout. N\u00e9anmoins, il fallait l\u00e0 encore ne       pas s\u2019attarder afin d\u2019\u00e9chapper aux coups qui impitoyablement s\u2019abattaient       sur les derniers.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Le rassemblement pour l\u2019appel avait lieu \u00e0 5 h.45,       l\u2019appel \u00e0 6 h.30, le d\u00e9part pour l\u2019usine \u00e0 6 h. <br \/>            Une raffinerie bien rep\u00e9r\u00e9e :<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            La raffinerie de p\u00e9trole dans laquelle nous travaillions et qui occupait       aussi des prisonniers de guerre fran\u00e7ais et anglais, \u00e9tait situ\u00e9e \u00e0 moins de       500 m\u00e8tres du camp.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Fortement encadr\u00e9es par des gardiens S.S., les \u00e9quipes \u2013       qui comprenaient entre 30 et 60 hommes \u2013 arrivaient sur leur chantier \u00e0 7       heures et se mettaient aussit\u00f4t au travail.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">L\u2019entreprise, d\u00e9j\u00e0 tr\u00e8s       s\u00e9v\u00e8rement touch\u00e9e par les bombes de la R.A.F., n\u2019en continuait pas moins \u00e0       recevoir la visite des aviateurs anglais.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Pratiquement, notre travail qui       consistait \u00e0 d\u00e9blayer les ruines, \u00e0 remettre en \u00e9tat de nombreuses       canalisations et \u00e0 r\u00e9parer les voies ferr\u00e9es transform\u00e9es en montagnes       russes, ne servait absolument \u00e0 rien.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Ce que nous accomplissions en huit       jours \u00e9tait automatiquement r\u00e9duit \u00e0 n\u00e9ant le neuvi\u00e8me et tout \u00e9tait \u00e0       recommencer.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Il va sans dire qu\u2019il en r\u00e9sultait un certain rel\u00e2chement dans le travail;       mais les \u201d Vorarbeiter \u201d  (condamn\u00e9s allemands faisant fonction de       contrema\u00eetres) nous rappelaient souvent \u00e0 l\u2019ordre et ne se trouvaient pas       embarrass\u00e9s pour stimuler notre \u00e9nergie : ils nous lan\u00e7aient dans les       mollets tout ce qui pouvait leur tomber sous la main.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            A n\u2019en pas douter, c\u2019\u00e9tait entre les \u201d Vorarbeiter \u201d des diff\u00e9rentes       \u00e9quipes, la lutte pour la prime de rendement !<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            A 10 heures, une pause de 10 minutes nous permettait de reprendre un peu de       souffle et deux heures plus tard, les \u201d Vorarbeiter \u201d assuraient sur le chantier       m\u00eame la distribution de notre soupe.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Fr\u00e9quemment, ils faisaient preuve de la plus flagrante injustice en       remplissant plus ou moins les deux louches auxquelles chaque d\u00e9tenu avait       droit; in\u00e9vitablement des querelles \u00e9clataient mais l\u2019ordre \u00e9tait       imm\u00e9diatement r\u00e9tabli par les \u201d Vorarbelter \u201d qui donnaient de violents coups de       louche sur la t\u00eate de ceux qui n\u2019avaient pas l\u2019heur de leur plaire.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Nous, Fran\u00e7ais, n\u2019\u00e9tions pas leurs pr\u00e9f\u00e9r\u00e9s, mais nous poss\u00e9dions l\u2019amiti\u00e9       des prisonniers de guerre fran\u00e7ais et anglais, qui, saisissant des occasions       favorables, venaient jusqu\u2019\u00e0 nous pour nous donner leur \u201d rabiot \u201c, il       fallait faire vite et, bien souvent, nous n\u2019e\u00fbmes m\u00eame pas le temps de       serrer la main de nos braves compagnons.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Le travail reprenait \u00e0 13 heures et       cinq heures durant les d\u00e9tenus accomplissaient leur lourde besogne       d\u2019esclaves. Aucune pause g\u00e9n\u00e9rale n\u2019\u00e9tait pr\u00e9vue dans l\u2019apr\u00e8s-midi mais, par       groupes de 10 ou 12 (sous la conduite d\u2019un gardien) les d\u00e9tenus de chaque       \u00e9quipe \u00e9taient autoris\u00e9s \u00e0 se rendre aux lieux d\u2019aisances situ\u00e9s en dehors       des chantiers. On gagnait l\u00e0 un temps pr\u00e9cieux car le nombre de \u201d places \u201d       se r\u00e9duisait \u00e0 quatre et chacun se faisait prier pour sortir. Plus d\u2019une       fois le gardien vint interrompre les derniers en les d\u00e9logeant \u00e0 coups de       crosse.<br \/>            La \u201d parade \u201d de rentr\u00e9e :<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            A 18 heures enfin les 1.600 d\u00e9tenus, las, couverts de poussi\u00e8re et       ruisselants de sueur, se rassemblaient et regagnaient le camp. A l\u2019entr\u00e9e se       tenaient le grand chef S.S., son Etat-Major et les Kapos ; malheur \u00e0 celui       dont le pas cadenc\u00e9 laissait \u00e0 d\u00e9sirer : Il \u00e9tait imm\u00e9diatement rou\u00e9 de       coups par les Kapos qui, sous l\u2019oeil de leur ma\u00eetre, se sentaient autoris\u00e9s       \u00e0 donner libre cours \u00e0 leurs instincts sanguinaires.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Lorsque les d\u00e9tenus avaient rejoint le camp, ils n\u2019avaient qu\u2019un seul souci       : celui de remplir leur ventre affam\u00e9. La nourriture du soir \u00e9tait plus       substantielle que la soupe du midi. Elle \u00e9tait amen\u00e9e dans plusieurs bacs       devant l\u2019entr\u00e9e de chaque tente et r\u00e9partie par les soins du Kapo et de       quelques \u201d Vorarbeiter \u201c.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Les 4.000 d\u00e9tenus, maintenus en files Indiennes par un       imposant service d\u2019ordre, d\u00e9filaient un \u00e0 un devant les pr\u00e9pos\u00e9s \u00e0 la       distribution et recevaient,dans leur gamelle, ce que comportait le menu du       jour.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Ainsi des pommes de terre ou des carottes non \u00e9pluch\u00e9es et non lav\u00e9es,       des sardines sal\u00e9es ou de la mortadelle \u2013 erzatz \u2013 nageaient dans la soupe aux       choux ou dans la soupe aux navets.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Les plus difficiles s\u2019\u00e9taient tr\u00e8s       rapidement accommod\u00e9s de cette p\u00e2t\u00e9e peu s\u00e9duisante car il fallait manger et       l\u2019on mangeait de bon app\u00e9tit; la longue et harassante journ\u00e9e de travail       pouvait excuser en partie notre gloutonnerie; mais ce qui l\u2019excusait       davantage, c\u2019\u00e9tait la crainte de tomber dans un guet-apens ou d\u2019\u00eatre       victimes de la bousculade journali\u00e8re, combin\u00e9e par des \u00eatres plus affam\u00e9s       que d\u2019autres, et au cours de laquelle, invariablement, le contenu des       gamelles se r\u00e9pandait \u00e0 terre.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">C\u2019\u00e9tait alors une m\u00eal\u00e9e g\u00e9n\u00e9rale pour la       possession de quelques pommes de terre, sardines ou feuilles de choux. Les       \u201cKapos\u201d et \u201cVorarbeiter\u201d demeuraient absolument indiff\u00e9rents       \u00e0 ce spectacle; jamais ils ne voulaient intervenir dans ces conflits qu\u2019ils       jugeaient insignifiants.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">A 20 heures, un coup de sifflet ramenait le calme dans le       camp. Tout le monde rentrait au \u201d bercail \u201d mais il fallait faire bien des       calculs au moment de p\u00e9n\u00e9trer dans la tente pour ne pas \u00eatre gratifi\u00e9 d\u2019un       dernier coup de gourdin de notre puissant seigneur.<br \/>            Triste week-end :<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">            Personne ne quittait le camp le samedi apr\u00e8s-midi. L\u2019emploi du temps       pr\u00e9voyait une s\u00e9rie de travaux de nettoyage et d\u2019entretien \u00e0 l\u2019ext\u00e9rieur et       \u00e0 l\u2019int\u00e9rieur de chaque baraque et, en plus, le passage aux \u201d douches \u201d de       tous les d\u00e9tenus.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Ces \u201d douches \u201d qui n\u2019\u00e9taient en fait qu\u2019un simple passage       sous les robinets grands ouverts, n\u2019attiraient cependant pas tout le monde;       quelques d\u00e9tenus essayaient de s\u2019y d\u00e9rober en se faufilant dans une baraque       voisine ou dans le refuge permanent qu\u2019offraient les lieux d\u2019aisances.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Cela       n\u2019\u00e9chappait pas toujours au \u201d Kapo \u201d ou \u00e0 ses d\u00e9vou\u00e9s informateurs qui       amenaient imm\u00e9diatement les d\u00e9linquants sous les robinets; ils leur       faisaient alors subir le supplice de la brosse \u00e0 chiendent jusqu\u2019\u00e0 ce que le       sang apparaisse sur leur peau tum\u00e9fi\u00e9e.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">Ce supplice durait parfois 10   minutes et les hurlements que ces malheureux faisaient entendre n\u2019avaient       plus rien d\u2019humain. Sous peine de subir le m\u00eame sort, nous ne pouvions pas       essayer d\u2019intervenir; nous \u00e9tions l\u00e0, impuissants devant le martyre de nos       camarades, impuissants surtout contre la cruaut\u00e9 du chef de bloc et de ses       acolytes.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">La journ\u00e9e du dimanche se d\u00e9roulait       g\u00e9n\u00e9ralement dans le calme; chacun s\u2019allongeait sur sa paillasse, se       laissant gagner par le sommeil<\/p>\n<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-bottom-right\"><a href=\"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2403?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" data-src=\"https:\/\/aassdn.org\/amicale\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;\" \/><\/a><a href=\"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2403?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Le Kommando venu de NEUENGAMME est employ\u00e9 au \u201d d\u00e9gagement \u201d des bombes non \u00e9clat\u00e9es et les matin\u00e9es de ce dangereux travail se passent \u00e0 approcher au plus pr\u00e8s et surtout au plus profond possible de l\u2019engin rep\u00e9r\u00e9 ce qui pla\u00e7ait alors les d\u00e9port\u00e9s \u00e0 l\u2019abri \u2026 des vues du personnel d\u2019escorte, celui-ci se tenant, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[114,79,99],"tags":[824,346,1164,419,214,238,1433,270],"class_list":["post-2403","post","type-post","status-publish","format-standard","hentry","category-europe-de-louest","category-extraits-de-bulletin","category-services-allemands","tag-deportation","tag-guerre","tag-kommando","tag-liberation","tag-resistance","tag-russie","tag-ss","tag-wehrmacht"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Souvenirs de deportation (2) | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Souvenirs de deportation (2) | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\" \/>\n<meta property=\"og:description\" content=\"Le Kommando venu de NEUENGAMME est employ\u00e9 au \u201d d\u00e9gagement \u201d des bombes non \u00e9clat\u00e9es et les matin\u00e9es de ce dangereux travail se passent \u00e0 approcher au plus pr\u00e8s et surtout au plus profond possible de l\u2019engin rep\u00e9r\u00e9 ce qui pla\u00e7ait alors les d\u00e9port\u00e9s \u00e0 l\u2019abri \u2026 des vues du personnel d\u2019escorte, celui-ci se tenant, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/\" \/>\n<meta property=\"og:site_name\" content=\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-29T08:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-15T13:07:03+00:00\" \/>\n<meta name=\"author\" content=\"AASSDN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AASSDN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/souvenirs-de-deportation-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/souvenirs-de-deportation-2\\\/\"},\"author\":{\"name\":\"AASSDN\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/person\\\/73800712a272e6d58a10a86ea9e59671\"},\"headline\":\"Souvenirs de deportation (2)\",\"datePublished\":\"2021-10-29T08:00:21+00:00\",\"dateModified\":\"2024-03-15T13:07:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/souvenirs-de-deportation-2\\\/\"},\"wordCount\":4155,\"publisher\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#organization\"},\"keywords\":[\"d\u00e9portation\",\"guerre\",\"kommando\",\"Lib\u00e9ration\",\"R\u00e9sistance\",\"Russie\",\"SS\",\"Wehrmacht\"],\"articleSection\":[\"Europe de l'Ouest\",\"Extraits de bulletin\",\"Services allemands\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/souvenirs-de-deportation-2\\\/\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/souvenirs-de-deportation-2\\\/\",\"name\":\"Souvenirs de deportation (2) | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#website\"},\"datePublished\":\"2021-10-29T08:00:21+00:00\",\"dateModified\":\"2024-03-15T13:07:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/souvenirs-de-deportation-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aassdn.org\\\/amicale\\\/souvenirs-de-deportation-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/souvenirs-de-deportation-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Souvenirs de deportation (2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#website\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/\",\"name\":\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\",\"description\":\"Services sp\u00e9ciaux : Des h\u00e9ros anonymes au service exclusif de la France\",\"publisher\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#organization\",\"name\":\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/wp-content\\\/uploads\\\/Logo_AASSDN_transparent2.png\",\"contentUrl\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/wp-content\\\/uploads\\\/Logo_AASSDN_transparent2.png\",\"width\":1832,\"height\":1609,\"caption\":\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\"},\"image\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/person\\\/73800712a272e6d58a10a86ea9e59671\",\"name\":\"AASSDN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g\",\"caption\":\"AASSDN\"},\"sameAs\":[\"https:\\\/\\\/aassdn.org\\\/amicale\"],\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/author\\\/wordpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Souvenirs de deportation (2) | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Souvenirs de deportation (2) | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","og_description":"Le Kommando venu de NEUENGAMME est employ\u00e9 au \u201d d\u00e9gagement \u201d des bombes non \u00e9clat\u00e9es et les matin\u00e9es de ce dangereux travail se passent \u00e0 approcher au plus pr\u00e8s et surtout au plus profond possible de l\u2019engin rep\u00e9r\u00e9 ce qui pla\u00e7ait alors les d\u00e9port\u00e9s \u00e0 l\u2019abri \u2026 des vues du personnel d\u2019escorte, celui-ci se tenant, [&hellip;]","og_url":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/","og_site_name":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","article_published_time":"2021-10-29T08:00:21+00:00","article_modified_time":"2024-03-15T13:07:03+00:00","author":"AASSDN","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"AASSDN","Dur\u00e9e de lecture estim\u00e9e":"20 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/#article","isPartOf":{"@id":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/"},"author":{"name":"AASSDN","@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/person\/73800712a272e6d58a10a86ea9e59671"},"headline":"Souvenirs de deportation (2)","datePublished":"2021-10-29T08:00:21+00:00","dateModified":"2024-03-15T13:07:03+00:00","mainEntityOfPage":{"@id":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/"},"wordCount":4155,"publisher":{"@id":"https:\/\/aassdn.org\/amicale\/#organization"},"keywords":["d\u00e9portation","guerre","kommando","Lib\u00e9ration","R\u00e9sistance","Russie","SS","Wehrmacht"],"articleSection":["Europe de l'Ouest","Extraits de bulletin","Services allemands"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/","url":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/","name":"Souvenirs de deportation (2) | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","isPartOf":{"@id":"https:\/\/aassdn.org\/amicale\/#website"},"datePublished":"2021-10-29T08:00:21+00:00","dateModified":"2024-03-15T13:07:03+00:00","breadcrumb":{"@id":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aassdn.org\/amicale\/souvenirs-de-deportation-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aassdn.org\/amicale\/"},{"@type":"ListItem","position":2,"name":"Souvenirs de deportation (2)"}]},{"@type":"WebSite","@id":"https:\/\/aassdn.org\/amicale\/#website","url":"https:\/\/aassdn.org\/amicale\/","name":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","description":"Services sp\u00e9ciaux : Des h\u00e9ros anonymes au service exclusif de la France","publisher":{"@id":"https:\/\/aassdn.org\/amicale\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aassdn.org\/amicale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aassdn.org\/amicale\/#organization","name":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","url":"https:\/\/aassdn.org\/amicale\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/logo\/image\/","url":"https:\/\/aassdn.org\/amicale\/wp-content\/uploads\/Logo_AASSDN_transparent2.png","contentUrl":"https:\/\/aassdn.org\/amicale\/wp-content\/uploads\/Logo_AASSDN_transparent2.png","width":1832,"height":1609,"caption":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux"},"image":{"@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/person\/73800712a272e6d58a10a86ea9e59671","name":"AASSDN","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g","caption":"AASSDN"},"sameAs":["https:\/\/aassdn.org\/amicale"],"url":"https:\/\/aassdn.org\/amicale\/author\/wordpress\/"}]}},"_links":{"self":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":0,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2403\/revisions"}],"wp:attachment":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/media?parent=2403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/categories?post=2403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/tags?post=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}