{"id":2393,"date":"2021-10-29T10:00:18","date_gmt":"2021-10-29T08:00:18","guid":{"rendered":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/"},"modified":"2024-03-02T15:22:25","modified_gmt":"2024-03-02T14:22:25","slug":"evolution-de-lassociation-louverture-jusquou-aller","status":"publish","type":"post","link":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/","title":{"rendered":"Evolution de l&#8217;association &#8211; L&#8217;ouverture : jusqu&#8217;ou aller ?"},"content":{"rendered":"<p class=\"Style29 Style28\" align=\"justify\"><em>Depuis plusieurs ann\u00e9es nos Assembl\u00e9es G\u00e9n\u00e9rales se sont inqui\u00e9t\u00e9es de la survie de notre Association. Le probl\u00e8me du recrutement a \u00e9t\u00e9 et demeure l\u2019une de nos pr\u00e9occupations majeures. Demain, c\u2019est-\u00e0-dire \u00e0 l\u2019occasion de notre prochain Congr\u00e8s du 12 au 15 mai 1988 \u00e0 Bordeaux, nos adh\u00e9rents seront saisis d\u2019un projet de modifications de nos statuts afin de permettre l\u2019ouverture de notre Amicale \u00e0 des g\u00e9n\u00e9rations plus jeunes. Lesquelles et comment? C\u2019est \u00e0 cela qu\u2019il faut r\u00e9fl\u00e9chir, c\u2019est pour cela qu\u2019il est donn\u00e9 ci-apr\u00e8s quelques \u00e9l\u00e9ments de r\u00e9flexion.<\/em><\/p>\n<p class=\"Style28 Style29\" align=\"justify\">\u00a0<\/p>\n<p class=\"Style28 Style29\" align=\"justify\"><strong>1\u00b0 Notre origine et nos buts :<\/strong> Nous les retrouverons r\u00e9sum\u00e9s sous la plume du G\u00e9n\u00e9ral L.RIVET, notre Patron de 1936 \u00e0 1944, \u00e0 la fois sur la page de nos statuts et sur celle de notre Bulletin.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\"><em>J\u2019en reproduis quelques phrases essentielles<\/em><\/p>\n<p class=\"Style28 Style29\" align=\"justify\">\u2026\u00ab Nouvelle par la densit\u00e9 de son titre, riche de son contenu fran\u00e7ais\u2026 Dans la chaude communaut\u00e9 des Anciens des Services Sp\u00e9ciaux, il y aura moins de souffrances et plus de joie \u00bb \u2026\u00ab Un pass\u00e9 riche de gloire et de services rendus au Pays. \u00bb Voil\u00e0 les raisons de notre Association et les seules. \u2026\u00ab L\u2019A.A.S.S.D.N., association de qualit\u00e9 qui a pris figure de groupement pilote parmi ceux vou\u00e9s \u00e0 des buts identiques \u00bb<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">\u00a0<\/p>\n<p class=\"Style28 Style29\" align=\"justify\"><strong>2\u00b0 Nos r\u00e9alisations:<\/strong> Nous nous sommes efforc\u00e9s depuis trente-cinq ans de rester fid\u00e8les \u00e0 ces affirmations de base. \u2026\u00ab Riches de notre contenu fran\u00e7ais \u00bb : Notre action nationale, d\u00e9pouill\u00e9e de toute coloration politique, a toujours d\u00e9fendu les int\u00e9r\u00eats et la grandeur de la France. Dans les grandes crises qui ont secou\u00e9 notre Pays, nous avons soutenu ce que nous pensions conforme \u00e0 l\u2019id\u00e9al de Patrie qui a conduit tant des n\u00f4tres au sacrifice. Ainsi voulions-nous d\u2019une fa\u00e7on ou d\u2019une autre garder l\u2019Alg\u00e9rie dans la France\u2026 Ainsi, plus r\u00e9cemment, avons-nous pris la d\u00e9fense des Services Sp\u00e9ciaux et de leurs collaborateurs dans les crises qui ont mis leur efficacit\u00e9 voire m\u00eame leur existence en cause.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">\u2026 \u00ab Un pass\u00e9 riche de gloire et de services rendus au Pays \u00bb Notre action morale n\u2019a cess\u00e9 de mettre en \u00e9vidence cette r\u00e9alit\u00e9 si souvent ignor\u00e9e, contest\u00e9e, parfois m\u00eame tendancieusement d\u00e9form\u00e9e. Notre M\u00e9morial de Ramatuelle est devenu le symbole national et respect\u00e9 de l\u2019histoire contemporaine des : \u00ab Services Sp\u00e9ciaux de la D\u00e9fense Nationale. \u00bb Nos r\u00e9unions nationales \u00e0 Paris et en province ont fait conna\u00eetre \u00e0 l\u2019opinion leur vrai visage. Des ouvrages de qualit\u00e9, parfois couronn\u00e9s de prix litt\u00e9raires, ont largement diffus\u00e9 et diffusent toujours en France et \u00e0 l\u2019\u00e9tranger la V\u00e9rit\u00e9 sur ce que fut notre vieille Maison, ses m\u00e9rites, ses r\u00e9alisations et aussi ses faiblesses. Nos r\u00e9actions devant les insultes, les oublis, les mensonges, s\u2019imposent d\u00e9sormais \u00e0 l\u2019audience des m\u00e9dias, comme \u00e0 celle des Fran\u00e7ais. Enfin, chaque fois que nous l\u2019avons pu \u2014 pas assez souvent \u00e0 notre gr\u00e9, nous avons aid\u00e9 nos camarades \u00e0 faire reconna\u00eetre leurs titres et leurs m\u00e9rites.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">\u2026 \u00ab Moins de souffrances et plus de joie \u00bb. Notre action sociale demeure prioritaire. Nous lui consacrons l\u2019essentiel de nos moyens financiers. En toutes circonstances, nous manifestons notre solidarit\u00e9, notre pr\u00e9sence aupr\u00e8s de ceux des n\u00f4tres qui sont dans la peine. A cet \u00e9gard, on ne saurait trop remercier la vigilance de nos d\u00e9l\u00e9gu\u00e9s et leur d\u00e9vouement si d\u00e9sint\u00e9ress\u00e9. Il reste pourtant que notre action sociale ne saurait \u00eatre compl\u00e8te si elle n\u00e9gligeait l\u2019aspect moral de notre mission. A cet \u00e9gard, notre Bulletin trimestriel demeure le lien irrempla\u00e7able entre nous. Je n\u2019oublie pas non plus le r\u00f4le humain de liaison jou\u00e9 en permanence avec tant de g\u00e9n\u00e9rosit\u00e9 et de gentillesse par nos secr\u00e9taires.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">\u2026\u00ab Groupement pilote \u00bb, nous le sommes si j\u2019en juge par les r\u00e9actions amicales que suscite notre fa\u00e7on d\u2019\u00eatre aupr\u00e8s des Associations amies. Mais \u00ab groupement pilote \u00bb sous-entend l\u2019id\u00e9e que nous avons des devoirs pour l\u2019avenir et sans doute un r\u00f4le dont il reste \u00e0 d\u00e9finir les contours. C\u2019est bien de cela qu\u2019il s\u2019agit d\u00e9sormais.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">\u00a0<\/p>\n<p class=\"Style28 Style29\" align=\"justify\"><strong>3\u00b0 L\u2019Avenir<\/strong>. Il est possible de l\u2019envisager de deux fa\u00e7ons:<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">a) Rester dans le statu quo, c\u2019est-\u00e0-dire limiter rigoureusement notre recrutement \u00e0 ceux qui ont appartenu aux Services Sp\u00e9ciaux de la Deuxi\u00e8me Guerre mondiale et \u00e0 leurs ayant droit (enfants, parents, etc\u2026) le Conseil d\u2019Administration accordant quelques d\u00e9rogations \u00e0 cette r\u00e8gle. C\u2019est sensiblement la situation actuelle. A plus ou moins long terme, elle voue notre Association \u00e0 la dissolution.<\/p>\n<p class=\"Style28 Style29\" align=\"justify\">b) Ouvrir notre Association aux Anciens des Services Sp\u00e9ciaux actuels, \u00e9tant entendu que leur adh\u00e9sion doit comporter l\u2019engagement de veiller scrupuleusement au respect de notre Pass\u00e9, de nos traditions et des principes de base qui ont pr\u00e9sid\u00e9 \u00e0 la cr\u00e9ation de notre Association. C\u2019est, en bref, les modifications que notre Conseil d\u2019Administration envisage de soumettre \u00e0 l\u2019appr\u00e9ciation de nos adh\u00e9rents<\/p>\n<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-bottom-right\"><a href=\"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2393?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" data-src=\"https:\/\/aassdn.org\/amicale\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"Afficher le PDF\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 32px; --smush-placeholder-aspect-ratio: 32\/32;\" \/><\/a><a href=\"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2393?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Depuis plusieurs ann\u00e9es nos Assembl\u00e9es G\u00e9n\u00e9rales se sont inqui\u00e9t\u00e9es de la survie de notre Association. Le probl\u00e8me du recrutement a \u00e9t\u00e9 et demeure l\u2019une de nos pr\u00e9occupations majeures. Demain, c\u2019est-\u00e0-dire \u00e0 l\u2019occasion de notre prochain Congr\u00e8s du 12 au 15 mai 1988 \u00e0 Bordeaux, nos adh\u00e9rents seront saisis d\u2019un projet de modifications de nos statuts [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79,101,80],"tags":[264,218,247,212],"class_list":["post-2393","post","type-post","status-publish","format-standard","hentry","category-extraits-de-bulletin","category-general-louis-rivet","category-historique-de-laassdn","tag-algerie","tag-congres","tag-general-louis-rivet","tag-memorial"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evolution de l&#039;association - L&#039;ouverture : jusqu&#039;ou aller ? | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evolution de l&#039;association - L&#039;ouverture : jusqu&#039;ou aller ? | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\" \/>\n<meta property=\"og:description\" content=\"Depuis plusieurs ann\u00e9es nos Assembl\u00e9es G\u00e9n\u00e9rales se sont inqui\u00e9t\u00e9es de la survie de notre Association. Le probl\u00e8me du recrutement a \u00e9t\u00e9 et demeure l\u2019une de nos pr\u00e9occupations majeures. Demain, c\u2019est-\u00e0-dire \u00e0 l\u2019occasion de notre prochain Congr\u00e8s du 12 au 15 mai 1988 \u00e0 Bordeaux, nos adh\u00e9rents seront saisis d\u2019un projet de modifications de nos statuts [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/\" \/>\n<meta property=\"og:site_name\" content=\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-29T08:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-02T14:22:25+00:00\" \/>\n<meta name=\"author\" content=\"AASSDN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AASSDN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/evolution-de-lassociation-louverture-jusquou-aller\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/evolution-de-lassociation-louverture-jusquou-aller\\\/\"},\"author\":{\"name\":\"AASSDN\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/person\\\/73800712a272e6d58a10a86ea9e59671\"},\"headline\":\"Evolution de l&#8217;association &#8211; L&#8217;ouverture : jusqu&#8217;ou aller ?\",\"datePublished\":\"2021-10-29T08:00:18+00:00\",\"dateModified\":\"2024-03-02T14:22:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/evolution-de-lassociation-louverture-jusquou-aller\\\/\"},\"wordCount\":876,\"publisher\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#organization\"},\"keywords\":[\"Alg\u00e9rie\",\"Congr\u00e8s\",\"G\u00e9n\u00e9ral Louis Rivet\",\"M\u00e9morial\"],\"articleSection\":[\"Extraits de bulletin\",\"G\u00e9n\u00e9ral Louis Rivet\",\"Historique de l'AASSDN\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/evolution-de-lassociation-louverture-jusquou-aller\\\/\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/evolution-de-lassociation-louverture-jusquou-aller\\\/\",\"name\":\"Evolution de l'association - L'ouverture : jusqu'ou aller ? | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#website\"},\"datePublished\":\"2021-10-29T08:00:18+00:00\",\"dateModified\":\"2024-03-02T14:22:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/evolution-de-lassociation-louverture-jusquou-aller\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aassdn.org\\\/amicale\\\/evolution-de-lassociation-louverture-jusquou-aller\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/evolution-de-lassociation-louverture-jusquou-aller\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evolution de l&#8217;association &#8211; L&#8217;ouverture : jusqu&#8217;ou aller ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#website\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/\",\"name\":\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\",\"description\":\"Services sp\u00e9ciaux : Des h\u00e9ros anonymes au service exclusif de la France\",\"publisher\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#organization\",\"name\":\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/wp-content\\\/uploads\\\/Logo_AASSDN_transparent2.png\",\"contentUrl\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/wp-content\\\/uploads\\\/Logo_AASSDN_transparent2.png\",\"width\":1832,\"height\":1609,\"caption\":\"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux\"},\"image\":{\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/#\\\/schema\\\/person\\\/73800712a272e6d58a10a86ea9e59671\",\"name\":\"AASSDN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g\",\"caption\":\"AASSDN\"},\"sameAs\":[\"https:\\\/\\\/aassdn.org\\\/amicale\"],\"url\":\"https:\\\/\\\/aassdn.org\\\/amicale\\\/author\\\/wordpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evolution de l'association - L'ouverture : jusqu'ou aller ? | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/","og_locale":"fr_FR","og_type":"article","og_title":"Evolution de l'association - L'ouverture : jusqu'ou aller ? | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","og_description":"Depuis plusieurs ann\u00e9es nos Assembl\u00e9es G\u00e9n\u00e9rales se sont inqui\u00e9t\u00e9es de la survie de notre Association. Le probl\u00e8me du recrutement a \u00e9t\u00e9 et demeure l\u2019une de nos pr\u00e9occupations majeures. Demain, c\u2019est-\u00e0-dire \u00e0 l\u2019occasion de notre prochain Congr\u00e8s du 12 au 15 mai 1988 \u00e0 Bordeaux, nos adh\u00e9rents seront saisis d\u2019un projet de modifications de nos statuts [&hellip;]","og_url":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/","og_site_name":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","article_published_time":"2021-10-29T08:00:18+00:00","article_modified_time":"2024-03-02T14:22:25+00:00","author":"AASSDN","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"AASSDN","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/#article","isPartOf":{"@id":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/"},"author":{"name":"AASSDN","@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/person\/73800712a272e6d58a10a86ea9e59671"},"headline":"Evolution de l&#8217;association &#8211; L&#8217;ouverture : jusqu&#8217;ou aller ?","datePublished":"2021-10-29T08:00:18+00:00","dateModified":"2024-03-02T14:22:25+00:00","mainEntityOfPage":{"@id":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/"},"wordCount":876,"publisher":{"@id":"https:\/\/aassdn.org\/amicale\/#organization"},"keywords":["Alg\u00e9rie","Congr\u00e8s","G\u00e9n\u00e9ral Louis Rivet","M\u00e9morial"],"articleSection":["Extraits de bulletin","G\u00e9n\u00e9ral Louis Rivet","Historique de l'AASSDN"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/","url":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/","name":"Evolution de l'association - L'ouverture : jusqu'ou aller ? | AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","isPartOf":{"@id":"https:\/\/aassdn.org\/amicale\/#website"},"datePublished":"2021-10-29T08:00:18+00:00","dateModified":"2024-03-02T14:22:25+00:00","breadcrumb":{"@id":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aassdn.org\/amicale\/evolution-de-lassociation-louverture-jusquou-aller\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aassdn.org\/amicale\/"},{"@type":"ListItem","position":2,"name":"Evolution de l&#8217;association &#8211; L&#8217;ouverture : jusqu&#8217;ou aller ?"}]},{"@type":"WebSite","@id":"https:\/\/aassdn.org\/amicale\/#website","url":"https:\/\/aassdn.org\/amicale\/","name":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","description":"Services sp\u00e9ciaux : Des h\u00e9ros anonymes au service exclusif de la France","publisher":{"@id":"https:\/\/aassdn.org\/amicale\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aassdn.org\/amicale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/aassdn.org\/amicale\/#organization","name":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux","url":"https:\/\/aassdn.org\/amicale\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/logo\/image\/","url":"https:\/\/aassdn.org\/amicale\/wp-content\/uploads\/Logo_AASSDN_transparent2.png","contentUrl":"https:\/\/aassdn.org\/amicale\/wp-content\/uploads\/Logo_AASSDN_transparent2.png","width":1832,"height":1609,"caption":"AASSDN | Anciens et Amis des Services Sp\u00e9ciaux"},"image":{"@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aassdn.org\/amicale\/#\/schema\/person\/73800712a272e6d58a10a86ea9e59671","name":"AASSDN","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9653808d17788562e72d77e426d8d02775774239aefd00a9b4e852423d8e9d7e?s=96&d=mm&r=g","caption":"AASSDN"},"sameAs":["https:\/\/aassdn.org\/amicale"],"url":"https:\/\/aassdn.org\/amicale\/author\/wordpress\/"}]}},"_links":{"self":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/comments?post=2393"}],"version-history":[{"count":0,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/posts\/2393\/revisions"}],"wp:attachment":[{"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/media?parent=2393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/categories?post=2393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aassdn.org\/amicale\/wp-json\/wp\/v2\/tags?post=2393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}